{"id":12019,"date":"2020-03-03T10:00:37","date_gmt":"2020-03-03T13:00:37","guid":{"rendered":"https:\/\/vaidebolsa.com.br\/?p=12019"},"modified":"2023-08-14T14:56:52","modified_gmt":"2023-08-14T17:56:52","slug":"fazer-medicina","status":"publish","type":"post","link":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/","title":{"rendered":"Como construir uma \u00f3tima carreira na sa\u00fade sem fazer medicina?"},"content":{"rendered":"<p>A carreira de medicina \u00e9 uma das mais cobi\u00e7adas de todas. Uma prova disso \u00e9 a dificuldade de aprova\u00e7\u00e3o em um vestibular do curso de medicina, tanto em universidades p\u00fablicas como privadas. Um dos pontos que mais atrai os estudantes para essa \u00e1rea s\u00e3o os sal\u00e1rios. No entanto, sabemos que essa profiss\u00e3o tamb\u00e9m tem desvantagens, como a alta carga de trabalho. Neste post. vamos provar para voc\u00ea que voc\u00ea pode seguir carreira na \u00e1rea da sa\u00fade sem precisar fazer medicina.<\/p>\n<p>A verdade \u00e9 que optar por fazer <a href=\"https:\/\/vaidebolsa.com.br\/como-e-o-curso-de-medicina\/\" target=\"_blank\" rel=\"noopener\">medicina<\/a> tem um pre\u00e7o alto. Em outras palavras, \u00e9 s\u00f3 pensar em quanto voc\u00ea ter\u00e1 que estudar para passar no <a href=\"https:\/\/vaidebolsa.com.br\/como-estudar-para-medicina\/\" target=\"_blank\" rel=\"noopener\">vestibular<\/a>. Em alguns casos, candidatos tentam por ano serem aprovados. Al\u00e9m disso, depois de ser aprovado, se for em uma institui\u00e7\u00e3o de ensino superior privada, vem a hora de pagar o valor alt\u00edssimo das mensalidades.<\/p>\n<p>Portanto, se voc\u00ea tem afinidade com a \u00e1rea da sa\u00fade, mas est\u00e1 repensando em fazer medicina ou n\u00e3o, temos algumas alternativas. H\u00e1 muitos cursos em institui\u00e7\u00f5es de qualidade\u00a0que valem a pena ter a sua aten\u00e7\u00e3o. Estamos falando de cursos como Enfermagem e <a href=\"https:\/\/vaidebolsa.com.br\/produto\/biomedicina-111-7034-11-3\/\" target=\"_blank\" rel=\"noopener\">Biomedicina<\/a>, al\u00e9m de uma ampla op\u00e7\u00e3o de cursos t\u00e9cnicos.<\/p>\n<p>Ficou interessado? Quer saber mais sobre o assunto? Ent\u00e3o acompanhe esse post at\u00e9 o final para ficar por dentro da \u00e1rea da medicina e tamb\u00e9m de outras carreiras na sa\u00fade.<\/p>\n<p><b>Leia tamb\u00e9m:<\/b><a href=\"https:\/\/vaidebolsa.com.br\/carreira-de-medico\/\"> <span style=\"font-weight: 400;\">Podcast Guia de Profiss\u00f5es: como \u00e9 a carreira de m\u00e9dico<\/span><\/a><\/p>\n<h2>As vantagens e desvantagens de fazer medicina<\/h2>\n<p>Se voc\u00ea est\u00e1 em d\u00favida em fazer ou n\u00e3o fazer medicina, precisa conhecer a fundo como \u00e9 o curso. Al\u00e9m disso, saber como \u00e9 o dia a dia da profiss\u00e3o. Em suma, as vantagens e desvantagens de atuar nessa \u00e1rea. Em primeiro lugar, voc\u00ea precisa saber que um curso de gradua\u00e7\u00e3o em medicina tem dura\u00e7\u00e3o de seis anos. Ou seja, \u00e9 uma longa caminhada para obter o diploma. Al\u00e9m disso, na maioria das vezes o curso \u00e9 em per\u00edodo integral. Voc\u00ea precisar\u00e1 dedicar todo o seu dia a ele.<\/p>\n<p>Em segundo lugar, precisa entender que a grade curricular durante esse per\u00edodo \u00e9 dividida em ciclos. Nos dois primeiros anos, s\u00e3o estudadas as disciplinas b\u00e1sicas, como anatomia, biologia celular, sa\u00fade da fam\u00edlia, entre outras. J\u00e1 no terceiro e quarto ano inicia o ciclo cl\u00ednico. \u00c9 aqui que o aluno vai receber no\u00e7\u00f5es de v\u00e1rias \u00e1reas da medicina, como neurologia, urologia, pediatria, por exemplo. J\u00e1 iniciam ent\u00e3o as visitas a hospitais e cl\u00ednicas.<\/p>\n<p>Por fim, os dois \u00faltimos anos terminam com o internato. \u00c9 a parte onde o aluno come\u00e7a a ter viv\u00eancia na profiss\u00e3o que escolheu. Aqui come\u00e7a o contato di\u00e1rio com pacientes em tratamento em hospitais e outras unidades de sa\u00fade.<\/p>\n<p>Ap\u00f3s todo esse per\u00edodo, voc\u00ea estar\u00e1 apto a receber o diploma de bacharel para se tornar m\u00e9dico. Agora, n\u00e3o cl\u00ednico-geral, por exemplo. Para isso, ser\u00e3o necess\u00e1rios mais dois a tr\u00eas anos de resid\u00eancia m\u00e9dica, como se fosse uma especializa\u00e7\u00e3o. O Conselho Federal de Medicina (CFM) reconhece 55 especializa\u00e7\u00f5es, desde pneumologista at\u00e9 ginecologista e cirurgi\u00e3o.<\/p>\n<p>Ufa! A maratona \u00e9 longa!<\/p>\n<p><strong>Leia tamb\u00e9m:<\/strong> <a href=\"https:\/\/vaidebolsa.com.br\/profissoes-com-foco-em-pesquisa\/\" target=\"_blank\" rel=\"noopener\">Quais s\u00e3o as profiss\u00f5es com foco em pesquisa na \u00e1rea da sa\u00fade?<\/a><\/p>\n<h3>As vantagens de fazer medicina<\/h3>\n<p>Agora, vamos ser mais espec\u00edficos. Confira as vantagens de fazer medicina e seguir a \u00e1rea m\u00e9dica:<\/p>\n<p>Voc\u00ea poder\u00e1 ajudar o pr\u00f3ximo &#8211; O conhecimento adquirido no curso de gradua\u00e7\u00e3o deixar\u00e1 voc\u00ea apto a promover a sa\u00fade, a curar doen\u00e7as e at\u00e9 a desenvolver vacinas. Ou seja, beneficiar a popula\u00e7\u00e3o.<\/p>\n<ul>\n<li><strong>Fortalece o emocional<\/strong> &#8211; Ser m\u00e9dico \u00e9 lidar com a vida das pessoas diariamente, sem medir esfor\u00e7os. Ao fazer isso, \u00e9 comum os pacientes darem um retorno emocional muito grande ao serem ajudados. Em outras palavras, a serem gratos pelo resto da vida.<\/li>\n<li><strong>Campo de atua\u00e7\u00e3o muito grande<\/strong> &#8211; Ao chegar na fase da resid\u00eancia m\u00e9dica, voc\u00ea ter\u00e1 um vasto campo de atua\u00e7\u00e3o para escolher. Poder\u00e1 atuar ainda como professor, gestor, pesquisador. Com uma <a href=\"https:\/\/vaidebolsa.com.br\/pos-graduacoes-mais-procuradas-da-medicina\/\" target=\"_blank\" rel=\"noopener\">p\u00f3s-gradua\u00e7\u00e3o em medicina<\/a>, pode ir ainda mais longe.<\/li>\n<li><strong>Carga hor\u00e1ria flex\u00edvel<\/strong> &#8211; O m\u00e9dico pode ajustar sua carga hor\u00e1ria de acordo com a sua conveni\u00eancia. \u00c9 claro que quanto mais plant\u00f5es fizer, maior ser\u00e1 o ganho financeiro. No entanto, \u00e9 poss\u00edvel cumprir hor\u00e1rios em consult\u00f3rios, hospitais, entre outras unidades. Aqui a disposi\u00e7\u00e3o far\u00e1 a diferen\u00e7a.<\/li>\n<li><strong>Sal\u00e1rio recompensador<\/strong> &#8211; Como j\u00e1 falamos, o sal\u00e1rio \u00e9 um dos principais atrativos da carreira m\u00e9dica. No entanto, saiba que o alto retorno financeiro vem quando se tem uma carga de trabalho elevada.<\/li>\n<\/ul>\n<h3>As desvantagens em fazer medicina<\/h3>\n<p>Para quem opta em fazer medicina, \u00e9 preciso estar muito certo disso. H\u00e1 tamb\u00e9m algumas inc\u00f4modas desvantagens:<\/p>\n<ul>\n<li><strong>Alta carga de trabalho<\/strong> &#8211; Se voc\u00ea acha que a <a href=\"https:\/\/vaidebolsa.com.br\/rotina-de-estudos\/\" target=\"_blank\" rel=\"noopener\">rotina de estudos<\/a> vai aliviar ap\u00f3s passar no vestibular para medicina, ou que sua vida j\u00e1 est\u00e1 ganha, est\u00e1 enganado. Come\u00e7a a\u00ed uma longa jornada de muito estudo e, ap\u00f3s formado, alta carga de trabalho. Fazer plant\u00f5es de madrugada, por exemplo, s\u00e3o bastante comuns.<\/li>\n<li><strong>Tempo com a fam\u00edlia fica reduzido<\/strong> &#8211; Justamente, por conta da alta carga de trabalho, o tempo junto com a sua fam\u00edlia pode ficar comprometido. Isso porque voc\u00ea ter\u00e1 que assumir compromissos em cl\u00ednicas e plant\u00f5es m\u00e9dicos. Isso pode afast\u00e1-lo um pouco do conv\u00edvio social. Sem falar das redes sociais e do WhatsApp, que podem ser o pesadelo de um m\u00e9dico.<\/li>\n<li><strong>Press\u00e3o dos pacientes<\/strong> &#8211; Quem est\u00e1 em tratamento por um m\u00e9dico espera sempre a cura imediata e voltar para casa. Se essa expectativa \u00e9 frustrada, prepare-se que l\u00e1 vem cr\u00edticas e muita press\u00e3o. Muitas vezes, a qualidade insatisfat\u00f3ria de um atendimento nem \u00e9 culpa do m\u00e9dico, e sim do sistema de sa\u00fade. Por\u00e9m&#8230;<\/li>\n<li><strong>Capacita\u00e7\u00e3o a todo momento<\/strong> &#8211; Um bom m\u00e9dico precisa estar constantemente atualizado na sua \u00e1rea de atua\u00e7\u00e3o. Ou seja, precisa buscar uma p\u00f3s-gradua\u00e7\u00e3o, participar de congressos e eventos da \u00e1rea, ler artigos cient\u00edficos e conversar com outros profissionais. Junte a isso a rotina estressante de trabalho!<\/li>\n<li><strong>Risco de processos m\u00e9dicos<\/strong> &#8211; Por lidar diariamente com a sa\u00fade de outras pessoas, o m\u00e9dico tamb\u00e9m est\u00e1 sujeito a erros, assim como qualquer profissional. No entanto, o erro do m\u00e9dico pode custar a vida do seu paciente e, com isso, processos judiciais e puni\u00e7\u00f5es. N\u00e3o \u00e9 f\u00e1cil!<\/li>\n<\/ul>\n<h2>Outras carreiras promissoras na \u00e1rea m\u00e9dica<\/h2>\n<p>Se ap\u00f3s ler at\u00e9 aqui voc\u00ea chegou \u00e0 conclus\u00e3o que fazer medicina n\u00e3o \u00e9 o seu perfil, n\u00e3o desanime. H\u00e1 v\u00e1rias carreiras na \u00e1rea da sa\u00fade muito interessantes e promissoras caso voc\u00ea tenha afinidade nesse tipo de profiss\u00e3o. Por essa raz\u00e3o, vamos listar algumas delas. Confira:<\/p>\n<ul>\n<li><a href=\"https:\/\/vaidebolsa.com.br\/como-e-o-curso-de-educacao-fisica\/\" target=\"_blank\" rel=\"noopener\">Educa\u00e7\u00e3o f\u00edsica<\/a><\/li>\n<li>Enfermagem<\/li>\n<li>Farm\u00e1cia<\/li>\n<li>Fonoaudiologia<\/li>\n<li>Nutri\u00e7\u00e3o<\/li>\n<li>Odontologia<\/li>\n<li>Psicologia<\/li>\n<li>Quiropraxia<\/li>\n<li>Fisioterapia<\/li>\n<li>Terapia Ocupacional<\/li>\n<li>Biomedicina<\/li>\n<li>Naturologia<\/li>\n<li>Obstetr\u00edcia<\/li>\n<li>Musicoterapia<\/li>\n<li>Est\u00e9tica<\/li>\n<\/ul>\n<p>Voc\u00ea conhece mais detalhes sobre cada uma delas no <a href=\"https:\/\/vaidebolsa.com.br\/\" target=\"_blank\" rel=\"noopener\">blog Vai de Bolsa<\/a>. H\u00e1 ainda muitas outras op\u00e7\u00f5es no mercado. Entre elas, cursos t\u00e9cnicos na <a href=\"https:\/\/vaidebolsa.com.br\/conheca-6-cursos-tecnicos-na-area-da-saude\/\" target=\"_blank\" rel=\"noopener\">\u00e1rea da sa\u00fade<\/a>, para quem busca uma forma\u00e7\u00e3o mais r\u00e1pida e, por consequ\u00eancia, entrar logo no mercado de trabalho.<\/p>\n<p>Al\u00e9m disso, sempre \u00e9 importante na hora de escolher a \u00e1rea a seguir, tamb\u00e9m escolher uma <a href=\"https:\/\/vaidebolsa.com.br\/blog\/universidades\/nota-do-mec\/\" target=\"_blank\" rel=\"noopener\">institui\u00e7\u00e3o de ensino reconhecida pelo Minist\u00e9rio da Educa\u00e7\u00e3o<\/a> (MEC) e de qualidade.<\/p>\n<h2><span style=\"font-weight: 100;\">Decidiu fazer medicina? Ou n\u00e3o?<\/span><\/h2>\n<p>E a\u00ed, decidiu fazer medicina ou partir para outra carreira na \u00e1rea de sa\u00fade? Qualquer que seja sua decis\u00e3o, boa sorte na sua trajet\u00f3ria!<\/p>\n<p>Acompanhe mais informa\u00e7\u00f5es sobre cursos, capacita\u00e7\u00f5es, mercado de trabalho, bolsas e dicas no <a href=\"https:\/\/vaidebolsa.com.br\/\" target=\"_blank\" rel=\"noopener\">blog Vai de Bolsa.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A carreira de medicina \u00e9 uma das mais cobi\u00e7adas de todas. Uma prova disso \u00e9 a dificuldade de aprova\u00e7\u00e3o em um vestibular do curso de medicina, tanto em universidades p\u00fablicas como privadas. Um dos pontos que mais atrai os estudantes para essa \u00e1rea s\u00e3o os sal\u00e1rios. No entanto, sabemos que essa profiss\u00e3o tamb\u00e9m tem desvantagens, [&hellip;]<\/p>\n","protected":false},"author":67,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[49],"tags":[],"class_list":["post-12019","post","type-post","status-publish","format-standard","hentry","category-graduacao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como construir uma carreira na sa\u00fade sem fazer medicina?<\/title>\n<meta name=\"description\" content=\"Seguir carreira na medicina tem suas vantagens e desvantanges. Por isso, vamos mostrar para voc\u00ea outras boas carreiras na sa\u00fade sem precisar fazer medicina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como construir uma carreira na sa\u00fade sem fazer medicina?\" \/>\n<meta property=\"og:description\" content=\"Seguir carreira na medicina tem suas vantagens e desvantanges. Por isso, vamos mostrar para voc\u00ea outras boas carreiras na sa\u00fade sem precisar fazer medicina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/\" \/>\n<meta property=\"og:site_name\" content=\"Vai de Bolsa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vdbeducacional\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-03T13:00:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-14T17:56:52+00:00\" \/>\n<meta name=\"author\" content=\"Natalia Pereira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Natalia Pereira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/\"},\"author\":{\"name\":\"Natalia Pereira\",\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/person\/66c9e3f3a84ba9e04deec23f2938a105\"},\"headline\":\"Como construir uma \u00f3tima carreira na sa\u00fade sem fazer medicina?\",\"datePublished\":\"2020-03-03T13:00:37+00:00\",\"dateModified\":\"2023-08-14T17:56:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/\"},\"wordCount\":1353,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#organization\"},\"articleSection\":[\"Gradua\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/\",\"url\":\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/\",\"name\":\"Como construir uma carreira na sa\u00fade sem fazer medicina?\",\"isPartOf\":{\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#website\"},\"datePublished\":\"2020-03-03T13:00:37+00:00\",\"dateModified\":\"2023-08-14T17:56:52+00:00\",\"description\":\"Seguir carreira na medicina tem suas vantagens e desvantanges. Por isso, vamos mostrar para voc\u00ea outras boas carreiras na sa\u00fade sem precisar fazer medicina.\",\"breadcrumb\":{\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/vaidebolsa.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como construir uma \u00f3tima carreira na sa\u00fade sem fazer medicina?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#website\",\"url\":\"https:\/\/vaidebolsa.com.br\/blog\/\",\"name\":\"Vai de Bolsa\",\"description\":\"Vai de Bolsa: Bolsas de Estudo com at\u00e9 70% de Desconto!\",\"publisher\":{\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vaidebolsa.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#organization\",\"name\":\"Vai de Bolsa\",\"url\":\"https:\/\/vaidebolsa.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/vaidebolsa.com.br\/blog\/wp-content\/uploads\/2022\/03\/Logo-Vai-de-Bolsa-cor-e1648649224262.png\",\"contentUrl\":\"https:\/\/vaidebolsa.com.br\/blog\/wp-content\/uploads\/2022\/03\/Logo-Vai-de-Bolsa-cor-e1648649224262.png\",\"width\":180,\"height\":90,\"caption\":\"Vai de Bolsa\"},\"image\":{\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/vdbeducacional\",\"https:\/\/www.instagram.com\/vaidebolsa_\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/person\/66c9e3f3a84ba9e04deec23f2938a105\",\"name\":\"Natalia Pereira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/f1ab57fb53849c617df1cb34eb8ae2d8?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/f1ab57fb53849c617df1cb34eb8ae2d8?s=96&d=mm&r=g\",\"caption\":\"Natalia Pereira\"},\"description\":\"Formada em Publicidade e Propaganda com bolsa de estudos, Nat\u00e1lia Pereira passou por todos os dilemas que envolvem a vida de um jovem que est\u00e1 prestes a sair do ensino m\u00e9dio e se depara com o desafio de entrar em uma boa faculdade pagando pouco. Hoje, aos 23 anos, atua como Analista de Marketing e escreve sobre educa\u00e7\u00e3o no Vai de Bolsa.\",\"url\":\"https:\/\/vaidebolsa.com.br\/blog\/author\/natalia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como construir uma carreira na sa\u00fade sem fazer medicina?","description":"Seguir carreira na medicina tem suas vantagens e desvantanges. Por isso, vamos mostrar para voc\u00ea outras boas carreiras na sa\u00fade sem precisar fazer medicina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/","og_locale":"pt_BR","og_type":"article","og_title":"Como construir uma carreira na sa\u00fade sem fazer medicina?","og_description":"Seguir carreira na medicina tem suas vantagens e desvantanges. Por isso, vamos mostrar para voc\u00ea outras boas carreiras na sa\u00fade sem precisar fazer medicina.","og_url":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/","og_site_name":"Vai de Bolsa","article_publisher":"https:\/\/www.facebook.com\/vdbeducacional","article_published_time":"2020-03-03T13:00:37+00:00","article_modified_time":"2023-08-14T17:56:52+00:00","author":"Natalia Pereira","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Natalia Pereira","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/#article","isPartOf":{"@id":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/"},"author":{"name":"Natalia Pereira","@id":"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/person\/66c9e3f3a84ba9e04deec23f2938a105"},"headline":"Como construir uma \u00f3tima carreira na sa\u00fade sem fazer medicina?","datePublished":"2020-03-03T13:00:37+00:00","dateModified":"2023-08-14T17:56:52+00:00","mainEntityOfPage":{"@id":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/"},"wordCount":1353,"commentCount":0,"publisher":{"@id":"https:\/\/vaidebolsa.com.br\/blog\/#organization"},"articleSection":["Gradua\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/","url":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/","name":"Como construir uma carreira na sa\u00fade sem fazer medicina?","isPartOf":{"@id":"https:\/\/vaidebolsa.com.br\/blog\/#website"},"datePublished":"2020-03-03T13:00:37+00:00","dateModified":"2023-08-14T17:56:52+00:00","description":"Seguir carreira na medicina tem suas vantagens e desvantanges. Por isso, vamos mostrar para voc\u00ea outras boas carreiras na sa\u00fade sem precisar fazer medicina.","breadcrumb":{"@id":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/fazer-medicina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vaidebolsa.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Como construir uma \u00f3tima carreira na sa\u00fade sem fazer medicina?"}]},{"@type":"WebSite","@id":"https:\/\/vaidebolsa.com.br\/blog\/#website","url":"https:\/\/vaidebolsa.com.br\/blog\/","name":"Vai de Bolsa","description":"Vai de Bolsa: Bolsas de Estudo com at\u00e9 70% de Desconto!","publisher":{"@id":"https:\/\/vaidebolsa.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vaidebolsa.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/vaidebolsa.com.br\/blog\/#organization","name":"Vai de Bolsa","url":"https:\/\/vaidebolsa.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/vaidebolsa.com.br\/blog\/wp-content\/uploads\/2022\/03\/Logo-Vai-de-Bolsa-cor-e1648649224262.png","contentUrl":"https:\/\/vaidebolsa.com.br\/blog\/wp-content\/uploads\/2022\/03\/Logo-Vai-de-Bolsa-cor-e1648649224262.png","width":180,"height":90,"caption":"Vai de Bolsa"},"image":{"@id":"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/vdbeducacional","https:\/\/www.instagram.com\/vaidebolsa_\/"]},{"@type":"Person","@id":"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/person\/66c9e3f3a84ba9e04deec23f2938a105","name":"Natalia Pereira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/f1ab57fb53849c617df1cb34eb8ae2d8?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/f1ab57fb53849c617df1cb34eb8ae2d8?s=96&d=mm&r=g","caption":"Natalia Pereira"},"description":"Formada em Publicidade e Propaganda com bolsa de estudos, Nat\u00e1lia Pereira passou por todos os dilemas que envolvem a vida de um jovem que est\u00e1 prestes a sair do ensino m\u00e9dio e se depara com o desafio de entrar em uma boa faculdade pagando pouco. Hoje, aos 23 anos, atua como Analista de Marketing e escreve sobre educa\u00e7\u00e3o no Vai de Bolsa.","url":"https:\/\/vaidebolsa.com.br\/blog\/author\/natalia\/"}]}},"_links":{"self":[{"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/posts\/12019"}],"collection":[{"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/users\/67"}],"replies":[{"embeddable":true,"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/comments?post=12019"}],"version-history":[{"count":1,"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/posts\/12019\/revisions"}],"predecessor-version":[{"id":17181321334,"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/posts\/12019\/revisions\/17181321334"}],"wp:attachment":[{"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/media?parent=12019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/categories?post=12019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/tags?post=12019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}