{"id":8624,"date":"2020-01-21T13:51:02","date_gmt":"2020-01-21T16:51:02","guid":{"rendered":"https:\/\/vaidebolsa.com.br\/?p=8624"},"modified":"2020-01-21T13:51:02","modified_gmt":"2020-01-21T16:51:02","slug":"curso-de-irrigacao-e-drenagem","status":"publish","type":"post","link":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/","title":{"rendered":"Conhe\u00e7a o curso de irriga\u00e7\u00e3o e drenagem: essencial para a produ\u00e7\u00e3o agr\u00edcola"},"content":{"rendered":"<p>Voc\u00ea sabia que o agroneg\u00f3cio \u00e9 um dos ramos que mais cresce no Brasil e no mundo? Por conta disso, muitos s\u00e3o os recursos dispensados para essa \u00e1rea t\u00e3o importante para o nosso pa\u00eds. Um deles \u00e9 o investimento em cursos especializados que visam a melhoria da produ\u00e7\u00e3o agr\u00edcola, que v\u00e3o muito al\u00e9m da <a href=\"https:\/\/vaidebolsa.com.br\/agronomia-saiba-tudo-sobre-o-curso-e-o-mercado-de-trabalho\/\" target=\"_blank\" rel=\"noopener\">agronomia<\/a>. Um exemplo disso \u00e9 curso de Irriga\u00e7\u00e3o e Drenagem. Neste post, voc\u00ea vai conhecer mais sobre o curso e porque ele \u00e9 t\u00e3o essencial para qualificar a produ\u00e7\u00e3o agr\u00edcola.<\/p>\n<p>H\u00e1 uma previs\u00e3o feita pela Ag\u00eancia Nacional de \u00c1gua (ANA) que at\u00e9 o ano de 2030 cerca de\u00a010 milh\u00f5es de hectares do territ\u00f3rio brasileiro ser\u00e3o irrigados por conta do agroneg\u00f3cio. E, para que essa irriga\u00e7\u00e3o seja feita de forma correta, sustent\u00e1vel e eficiente, se faz necess\u00e1rio um profissional especializado em irriga\u00e7\u00e3o e drenagem.<\/p>\n<p>A import\u00e2ncia da profiss\u00e3o de irriga\u00e7\u00e3o e drenagem para a produ\u00e7\u00e3o agr\u00edcola \u00e9 dar conta desse crescimento da necessidade de recursos referentes \u00e0 irriga\u00e7\u00e3o no agroneg\u00f3cio, feito com conhecimento e compet\u00eancia. \u00c9 um curso que lida com quest\u00f5es importantes do <a href=\"https:\/\/vaidebolsa.com.br\/cursos-ligados-ao-meio-ambiente\/\" target=\"_blank\" rel=\"noopener\">meio ambiente<\/a>.<\/p>\n<p>Quer saber mais sobre o curso e o mercado de trabalho na \u00e1rea? Esse post \u00e9 para voc\u00ea.<\/p>\n<h2>O que \u00e9 e para que serve a irriga\u00e7\u00e3o?<\/h2>\n<p>Irriga\u00e7\u00e3o \u00e9 uma t\u00e9cnica antiga que foi desenvolvida cerca de 500 anos a.C. Ela utiliza o fornecimento controlado da \u00e1gua para as plantas. Essa quantidade deve ser estudada para que seja aplicada no momento certo e adequada para o tipo de planta\u00e7\u00e3o para assegurar sua produtividade e sobreviv\u00eancia.<\/p>\n<p>A irriga\u00e7\u00e3o pode ser feita de diversas maneiras. Estas podem ser definidas por fatores como o tipo de terreno, de solo ou tipo de planta\u00e7\u00e3o. At\u00e9 a quantidade de \u00e1gua dispon\u00edvel influencia o tipo de irriga\u00e7\u00e3o que ser\u00e1 feito. Alguns exemplos s\u00e3o: por gravidade, ou escorrimento; por submers\u00e3o em terrenos planos ou por gota a gota.<\/p>\n<p>A irriga\u00e7\u00e3o serve para que se tenha um ganho de produtividade da agricultura, j\u00e1 que a popula\u00e7\u00e3o mundial s\u00f3 cresce e precisa ser alimentada. Ela deve ser feita de forma consciente, tamb\u00e9m pensando nos impactos ambientais que poder\u00e1 causar.<\/p>\n<p><strong>Leia mais:<\/strong> <a href=\"https:\/\/vaidebolsa.com.br\/como-e-o-curso-de-gestao-ambiental\/\" target=\"_blank\" rel=\"noopener\">Como \u00e9 o curso e o mercado de trabalho em gest\u00e3o ambiental<\/a><\/p>\n<h2>Import\u00e2ncia da irriga\u00e7\u00e3o na produ\u00e7\u00e3o agr\u00edcola<\/h2>\n<p>A produ\u00e7\u00e3o agr\u00edcola em m\u00e9dia e larga escala praticamente tem como obrigat\u00f3rio o controle da irriga\u00e7\u00e3o. Ela permite melhorar os resultados da produ\u00e7\u00e3o.<\/p>\n<p>Para fazer uma boa irriga\u00e7\u00e3o, deve-se levar em conta o clima do local, o tipo de solo e o tipo de plantio. Assim, pode-se definir melhor o tipo de irriga\u00e7\u00e3o que ser\u00e1 feito, conforme mencionamos.<\/p>\n<p>Atrav\u00e9s da irriga\u00e7\u00e3o, \u00e9 poss\u00edvel o plantio no ano todo, podendo n\u00e3o levar em considera\u00e7\u00e3o \u00e9pocas de chuva. Dessa maneira pode-se garantir a produ\u00e7\u00e3o em qualquer \u00e9poca do ano. Os agricultores conseguem, ent\u00e3o,\u00a0cultivar em diferentes \u00e9pocas, tendo a possibilidade de colheitas na entressafra.<\/p>\n<h2>Como \u00e9 o Curso de Irriga\u00e7\u00e3o e Drenagem?<\/h2>\n<p>O curso de Irriga\u00e7\u00e3o e Drenagem \u00e9 um curso de n\u00edvel superior, do tipo <a href=\"https:\/\/vaidebolsa.com.br\/diferenca-entre-tecnologo-e-bacharelado\/\" target=\"_blank\" rel=\"noopener\">tecnol\u00f3gico<\/a>, com dura\u00e7\u00e3o m\u00e9dia de 3 a 3,5 anos. A forma de ingresso \u00e9 pelo Sistema de Sele\u00e7\u00e3o Unificada (<a href=\"https:\/\/vaidebolsa.com.br\/sisu\/\" target=\"_blank\" rel=\"noopener\">SISU<\/a>) e \u00e9 necess\u00e1rio ter conclu\u00eddo o ensino m\u00e9dio. O curso \u00e9 integral.<\/p>\n<p>Confira a grade curricular do Curso de Irriga\u00e7\u00e3o e Drenagem:<\/p>\n<h3>Grade Curricular do Curso de Irriga\u00e7\u00e3o e Drenagem<\/h3>\n<p>Como exemplo da grade curricular, temos o curso oferecido gratuitamente pelo Instituto Federal de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia do Cear\u00e1 (IFCE), na cidade de Sobral. O instituto\u00a0nasceu da integra\u00e7\u00e3o do Centro Federal de Educa\u00e7\u00e3o Tecnol\u00f3gica do Cear\u00e1 (CEFETCE) com as Escolas Agrot\u00e9cnicas Federais de Crato de Iguatu.<\/p>\n<p>O curso tem dura\u00e7\u00e3o de 7 per\u00edodos, ou seja, 3 anos e meio, e oferece 35 vagas por semestre. Segue a grade:<\/p>\n<ul>\n<li><strong>1\u00ba Per\u00edodo:<\/strong> C\u00e1lculo; F\u00edsica Aplicada; Biologia Aplicada; Qu\u00edmica Aplicada; Inform\u00e1tica; Ingl\u00eas Instrumental e Introdu\u00e7\u00e3o \u00e0 Tecnologia.<\/li>\n<li><strong>2\u00ba Per\u00edodo:<\/strong> Desenho B\u00e1sico e Topogr\u00e1fico; Estat\u00edstica; Metodologia do Trabalho Cient\u00edfico; Hidr\u00e1ulica e Hidrot\u00e9cnica; G\u00eanese e F\u00edsica do Solo e Meteorologia Aplicada \u00e0 Irriga\u00e7\u00e3o.<\/li>\n<li><strong>3\u00ba Per\u00edodo:<\/strong> Topografia; Inform\u00e1tica Aplicada ao CAD; Salinidade do Solo e Qualidade da \u00c1gua para Irriga\u00e7\u00e3o; Hidrologia Aplicada; Ecologia Aplicada; Qu\u00edmica e Fertilidade do Solo e Rela\u00e7\u00e3o \u00c1gua-Solo-Planta.<\/li>\n<li><strong>4\u00ba Per\u00edodo:<\/strong> Fitossanidade; Mecaniza\u00e7\u00e3o Agr\u00edcola; Irriga\u00e7\u00e3o por Superf\u00edcie; Irriga\u00e7\u00e3o por Aspers\u00e3o; Irriga\u00e7\u00e3o Localizada; Drenagem Agr\u00edcola e Higiene e Seguran\u00e7a do Trabalho.<\/li>\n<li><strong>5\u00ba Per\u00edodo:<\/strong> Legisla\u00e7\u00e3o e Gest\u00e3o de Recursos H\u00eddricos; Opera\u00e7\u00e3o e Manuten\u00e7\u00e3o de Sistemas Irrigados; Manejo de Culturas Anuais Irrigadas; Manejo, Controle e Avalia\u00e7\u00e3o de Sistemas de Irriga\u00e7\u00e3o; Quimiga\u00e7\u00e3o e Projetos de Irriga\u00e7\u00e3o e Drenagem.<\/li>\n<li><strong>6\u00ba Per\u00edodo:<\/strong> Empreendedorismo e Gest\u00e3o Empresarial; Conserva\u00e7\u00e3o de Solo, \u00c1gua e Energia; Administra\u00e7\u00e3o Rural; Obras Hidr\u00e1ulicas; Manejo de Fruteiras; Sociologia e Extens\u00e3o Rural e Inform\u00e1tica Aplicada \u00e0 Irriga\u00e7\u00e3o. Como disciplina optativa nessa fase, \u00e9 poss\u00edvel cursar Libras &#8211; L\u00edngua Brasileira de Sinais.<\/li>\n<li><strong>7\u00ba Per\u00edodo:<\/strong> Neste per\u00edodo, o estudante realiza seu est\u00e1gio e pode cursar outras optativas. S\u00e3o elas: Cooperativismo; Agricultura Org\u00e2nica e Poliniza\u00e7\u00e3o Dirigida.<\/li>\n<\/ul>\n<h2>Atividades do tecn\u00f3logo em Irriga\u00e7\u00e3o e Drenagem<\/h2>\n<p>Quem faz o curso de Irriga\u00e7\u00e3o e Drenagem pode trabalhar com an\u00e1lise de altera\u00e7\u00f5es f\u00edsico-qu\u00edmicas que a \u00e1gua provoca no solo e as necessidades das planta\u00e7\u00f5es. O tecn\u00f3logo ter\u00e1 capacidade para fazer projetos de irriga\u00e7\u00e3o, avalia\u00e7\u00e3o do solo, levantamento topogr\u00e1fico e orientar a utiliza\u00e7\u00e3o de produtos qu\u00edmicos.<\/p>\n<p>Tamb\u00e9m define a distribui\u00e7\u00e3o de \u00e1gua, constru\u00e7\u00e3o de canais e instala\u00e7\u00e3o de bombas. Preocupa-se com a influ\u00eancia do seu trabalho em rela\u00e7\u00e3o ao meio ambiente. Tamb\u00e9m controla a utiliza\u00e7\u00e3o de fertilizantes nas planta\u00e7\u00f5es.<\/p>\n<p>Deve estar atento \u00e0s novas tecnologias, ou at\u00e9 criando-as, para o uso racional da \u00e1gua.<\/p>\n<p>Faz implanta\u00e7\u00e3o de culturas, prepara\u00e7\u00e3o das \u00e1reas para serem irrigadas, elabora projetos de conten\u00e7\u00e3o e represamento. Tamb\u00e9m faz avalia\u00e7\u00e3o de desempenho de sistemas, m\u00e1quinas e equipamentos de irriga\u00e7\u00e3o.<\/p>\n<p><strong>Leia mais:<\/strong> <a href=\"https:\/\/vaidebolsa.com.br\/engenharia-hidrica\/\" target=\"_blank\" rel=\"noopener\">Estiagem e crise geram oportunidades na Engenharia H\u00eddrica<\/a><\/p>\n<h2>Mercado de trabalho para quem faz o curso de Irriga\u00e7\u00e3o e Drenagem<\/h2>\n<p>O mercado de trabalho normalmente \u00e9 voltado para a produ\u00e7\u00e3o agr\u00edcola de grande e m\u00e9dio porte. Ou ent\u00e3o para empresas que trabalham com o ramo de irriga\u00e7\u00e3o, seja vendendo produtos ou oferecendo servi\u00e7os.<\/p>\n<p>Com a irregularidade das chuvas no Brasil, o mercado para que faz o curso de Irriga\u00e7\u00e3o e Drenagem est\u00e1 crescendo e se tornando mais necess\u00e1rio. Os fazendeiros tem procurado cada vez mais esses especialistas para auxiliarem tamb\u00e9m no uso racional da \u00e1gua em suas propriedades.<\/p>\n<p>Goi\u00e1s \u00e9 considerado hoje, o estado que mais necessita deste profissional por ser o estado mais irrigado do pa\u00eds. Outros estados que tamb\u00e9m tem essa demanda s\u00e3o:\u00a0Roraima, Mato Grosso do Sul, Par\u00e1, Pernambuco, Bahia e Cear\u00e1. J\u00e1 no Sul e Sudeste, as buscas por esse profissional acontecem mais em ind\u00fastrias ou fabricantes e revendedores de produtos de sistemas de irriga\u00e7\u00e3o.<\/p>\n<h3>Onde cursar Irriga\u00e7\u00e3o e Drenagem<\/h3>\n<p>Ainda s\u00e3o poucas as institui\u00e7\u00f5es que oferecem o curso de Irriga\u00e7\u00e3o e Drenagem. Temos aqui dois institutos no estado do Cear\u00e1:<\/p>\n<ul>\n<li>Instituto Federal de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia do Cear\u00e1 (IFCE), em Sobral (CE) &#8211; gratuito;<\/li>\n<li>Instituto Centro de Ensino Tecnol\u00f3gico (CENTEC), em Fortaleza (CE) &#8211; gratuito.<\/li>\n<\/ul>\n<h2>Quanto ganha um Tecn\u00f3logo em Irriga\u00e7\u00e3o e Drenagem?<\/h2>\n<p>Segundo o site Educa Mais Brasil, o tecn\u00f3logo em Irriga\u00e7\u00e3o e Drenagem ganha no in\u00edcio de carreira, como <a href=\"https:\/\/vaidebolsa.com.br\/trainee-saiba-o-que-e-e-quais-as-vantagens-de-ser-um\/\" target=\"_blank\" rel=\"noopener\">trainee<\/a>, em uma empresa pequena, um sal\u00e1rio de\u00a0R$\u00a02.506,53. J\u00e1 como master em uma empresa de grande porte, o sal\u00e1rio m\u00e9dio \u00e9 de\u00a0R$\u00a03.620,98. As informa\u00e7\u00f5es foram retiradas do\u00a0Site Nacional de Empregos (SINE).<\/p>\n<p>J\u00e1 no site Trabalha Brasil, os sal\u00e1rios variam de\u00a0R$ 1.916,44 para trainee em empresa pequena e\u00a0R$ 7.907,19 para master em uma empresa de grande porte.<\/p>\n<h2>Curso de Irriga\u00e7\u00e3o e Drenagem x Engenharia Agr\u00edcola<\/h2>\n<p>O curso de Irriga\u00e7\u00e3o e Drenagem \u00e9 de n\u00edvel tecnol\u00f3gico, enquanto o de Engenharia Agr\u00edcola \u00e9 bacharelado. S\u00f3 isso j\u00e1 \u00e9 uma grande diferen\u00e7a pois os cursos tecnol\u00f3gicos tem uma \u00eanfase maior no mercado de trabalho e tem dura\u00e7\u00e3o mais curta.<\/p>\n<p>No curso de Engenharia Agr\u00edcola, o profissional \u00e9 preparado para gerenciar processos das \u00e1reas de agropecu\u00e1ria, levando em conta quest\u00f5es socioecon\u00f4micas e ambientais, al\u00e9m do conhecimento geral da engenharia. Projeta t\u00e9cnicas e equipamentos\u00a0 e implementa m\u00e9todos de armazenagem.<\/p>\n<p>J\u00e1 o tecn\u00f3logo de Irriga\u00e7\u00e3o e Drenagem tem como foco maior de trabalho a assist\u00eancia ao plantio e suas necessidades.\u00a0O profissional de irriga\u00e7\u00e3o e drenagem e o engenheiro agr\u00edcola costumam trabalhar em parceria.<\/p>\n<p>Se interessou pelo curso de Irriga\u00e7\u00e3o e Drenagem? Saiba mais sobre outros cursos relacionados \u00e0 agricultura e outros assuntos no nosso <a href=\"https:\/\/vaidebolsa.com.br\/\" target=\"_blank\" rel=\"noopener\">blog Vai de Bolsa<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea sabia que o agroneg\u00f3cio \u00e9 um dos ramos que mais cresce no Brasil e no mundo? Por conta disso, muitos s\u00e3o os recursos dispensados para essa \u00e1rea t\u00e3o importante para o nosso pa\u00eds. Um deles \u00e9 o investimento em cursos especializados que visam a melhoria da produ\u00e7\u00e3o agr\u00edcola, que v\u00e3o muito al\u00e9m da agronomia. [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[49],"tags":[],"class_list":["post-8624","post","type-post","status-publish","format-standard","hentry","category-graduacao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Curso de irriga\u00e7\u00e3o e drenagem: essencial para a produ\u00e7\u00e3o agr\u00edcola<\/title>\n<meta name=\"description\" content=\"Saiba tudo sobre o curso de irriga\u00e7\u00e3o e drenagem. Saiba qual a import\u00e2ncia do curso de irriga\u00e7\u00e3o e drenagem para a produ\u00e7\u00e3o agr\u00edcola.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curso de irriga\u00e7\u00e3o e drenagem: essencial para a produ\u00e7\u00e3o agr\u00edcola\" \/>\n<meta property=\"og:description\" content=\"Saiba tudo sobre o curso de irriga\u00e7\u00e3o e drenagem. Saiba qual a import\u00e2ncia do curso de irriga\u00e7\u00e3o e drenagem para a produ\u00e7\u00e3o agr\u00edcola.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/\" \/>\n<meta property=\"og:site_name\" content=\"Vai de Bolsa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vdbeducacional\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-21T16:51:02+00:00\" \/>\n<meta name=\"author\" content=\"Aline Almeida\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aline Almeida\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/\"},\"author\":{\"name\":\"Aline Almeida\",\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/person\/55414b48a1dd5d9ac90703e8f08544da\"},\"headline\":\"Conhe\u00e7a o curso de irriga\u00e7\u00e3o e drenagem: essencial para a produ\u00e7\u00e3o agr\u00edcola\",\"datePublished\":\"2020-01-21T16:51:02+00:00\",\"dateModified\":\"2020-01-21T16:51:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/\"},\"wordCount\":1577,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#organization\"},\"articleSection\":[\"Gradua\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/\",\"url\":\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/\",\"name\":\"Curso de irriga\u00e7\u00e3o e drenagem: essencial para a produ\u00e7\u00e3o agr\u00edcola\",\"isPartOf\":{\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#website\"},\"datePublished\":\"2020-01-21T16:51:02+00:00\",\"dateModified\":\"2020-01-21T16:51:02+00:00\",\"description\":\"Saiba tudo sobre o curso de irriga\u00e7\u00e3o e drenagem. Saiba qual a import\u00e2ncia do curso de irriga\u00e7\u00e3o e drenagem para a produ\u00e7\u00e3o agr\u00edcola.\",\"breadcrumb\":{\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/vaidebolsa.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conhe\u00e7a o curso de irriga\u00e7\u00e3o e drenagem: essencial para a produ\u00e7\u00e3o agr\u00edcola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#website\",\"url\":\"https:\/\/vaidebolsa.com.br\/blog\/\",\"name\":\"Vai de Bolsa\",\"description\":\"Vai de Bolsa: Bolsas de Estudo com at\u00e9 70% de Desconto!\",\"publisher\":{\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vaidebolsa.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#organization\",\"name\":\"Vai de Bolsa\",\"url\":\"https:\/\/vaidebolsa.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/vaidebolsa.com.br\/blog\/wp-content\/uploads\/2022\/03\/Logo-Vai-de-Bolsa-cor-e1648649224262.png\",\"contentUrl\":\"https:\/\/vaidebolsa.com.br\/blog\/wp-content\/uploads\/2022\/03\/Logo-Vai-de-Bolsa-cor-e1648649224262.png\",\"width\":180,\"height\":90,\"caption\":\"Vai de Bolsa\"},\"image\":{\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/vdbeducacional\",\"https:\/\/www.instagram.com\/vaidebolsa_\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/person\/55414b48a1dd5d9ac90703e8f08544da\",\"name\":\"Aline Almeida\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/7d505c7607835f46feaecf0bc34c4234?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/7d505c7607835f46feaecf0bc34c4234?s=96&d=mm&r=g\",\"caption\":\"Aline Almeida\"},\"url\":\"https:\/\/vaidebolsa.com.br\/blog\/author\/aline-almeida\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Curso de irriga\u00e7\u00e3o e drenagem: essencial para a produ\u00e7\u00e3o agr\u00edcola","description":"Saiba tudo sobre o curso de irriga\u00e7\u00e3o e drenagem. Saiba qual a import\u00e2ncia do curso de irriga\u00e7\u00e3o e drenagem para a produ\u00e7\u00e3o agr\u00edcola.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/","og_locale":"pt_BR","og_type":"article","og_title":"Curso de irriga\u00e7\u00e3o e drenagem: essencial para a produ\u00e7\u00e3o agr\u00edcola","og_description":"Saiba tudo sobre o curso de irriga\u00e7\u00e3o e drenagem. Saiba qual a import\u00e2ncia do curso de irriga\u00e7\u00e3o e drenagem para a produ\u00e7\u00e3o agr\u00edcola.","og_url":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/","og_site_name":"Vai de Bolsa","article_publisher":"https:\/\/www.facebook.com\/vdbeducacional","article_published_time":"2020-01-21T16:51:02+00:00","author":"Aline Almeida","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Aline Almeida","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/#article","isPartOf":{"@id":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/"},"author":{"name":"Aline Almeida","@id":"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/person\/55414b48a1dd5d9ac90703e8f08544da"},"headline":"Conhe\u00e7a o curso de irriga\u00e7\u00e3o e drenagem: essencial para a produ\u00e7\u00e3o agr\u00edcola","datePublished":"2020-01-21T16:51:02+00:00","dateModified":"2020-01-21T16:51:02+00:00","mainEntityOfPage":{"@id":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/"},"wordCount":1577,"commentCount":0,"publisher":{"@id":"https:\/\/vaidebolsa.com.br\/blog\/#organization"},"articleSection":["Gradua\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/","url":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/","name":"Curso de irriga\u00e7\u00e3o e drenagem: essencial para a produ\u00e7\u00e3o agr\u00edcola","isPartOf":{"@id":"https:\/\/vaidebolsa.com.br\/blog\/#website"},"datePublished":"2020-01-21T16:51:02+00:00","dateModified":"2020-01-21T16:51:02+00:00","description":"Saiba tudo sobre o curso de irriga\u00e7\u00e3o e drenagem. Saiba qual a import\u00e2ncia do curso de irriga\u00e7\u00e3o e drenagem para a produ\u00e7\u00e3o agr\u00edcola.","breadcrumb":{"@id":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vaidebolsa.com.br\/blog\/graduacao\/curso-de-irrigacao-e-drenagem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vaidebolsa.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Conhe\u00e7a o curso de irriga\u00e7\u00e3o e drenagem: essencial para a produ\u00e7\u00e3o agr\u00edcola"}]},{"@type":"WebSite","@id":"https:\/\/vaidebolsa.com.br\/blog\/#website","url":"https:\/\/vaidebolsa.com.br\/blog\/","name":"Vai de Bolsa","description":"Vai de Bolsa: Bolsas de Estudo com at\u00e9 70% de Desconto!","publisher":{"@id":"https:\/\/vaidebolsa.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vaidebolsa.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/vaidebolsa.com.br\/blog\/#organization","name":"Vai de Bolsa","url":"https:\/\/vaidebolsa.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/vaidebolsa.com.br\/blog\/wp-content\/uploads\/2022\/03\/Logo-Vai-de-Bolsa-cor-e1648649224262.png","contentUrl":"https:\/\/vaidebolsa.com.br\/blog\/wp-content\/uploads\/2022\/03\/Logo-Vai-de-Bolsa-cor-e1648649224262.png","width":180,"height":90,"caption":"Vai de Bolsa"},"image":{"@id":"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/vdbeducacional","https:\/\/www.instagram.com\/vaidebolsa_\/"]},{"@type":"Person","@id":"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/person\/55414b48a1dd5d9ac90703e8f08544da","name":"Aline Almeida","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/vaidebolsa.com.br\/blog\/#\/schema\/person\/image\/","url":"http:\/\/1.gravatar.com\/avatar\/7d505c7607835f46feaecf0bc34c4234?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/7d505c7607835f46feaecf0bc34c4234?s=96&d=mm&r=g","caption":"Aline Almeida"},"url":"https:\/\/vaidebolsa.com.br\/blog\/author\/aline-almeida\/"}]}},"_links":{"self":[{"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/posts\/8624"}],"collection":[{"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/comments?post=8624"}],"version-history":[{"count":0,"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/posts\/8624\/revisions"}],"wp:attachment":[{"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/media?parent=8624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/categories?post=8624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vaidebolsa.com.br\/blog\/wp-json\/wp\/v2\/tags?post=8624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}